{"id":83,"date":"2021-07-01T11:16:40","date_gmt":"2021-07-01T09:16:40","guid":{"rendered":"https:\/\/luxurycandlesupplies.eu\/?post_type=product&#038;p=83"},"modified":"2026-07-15T10:15:28","modified_gmt":"2026-07-15T08:15:28","slug":"s16-soja-de-lujo-15kg","status":"publish","type":"product","link":"https:\/\/luxurycandlesupplies.eu\/es\/product\/s16-deluxe-soy-15kg\/","title":{"rendered":"S16 Deluxe Soja - 15kg"},"content":{"rendered":"<h2>DESCRIPCI\u00d3N<\/h2>\n<p>&nbsp;<\/p>\n<hr \/>\n<div><\/div>\n<p>&nbsp;<\/p>\n<h3>SOJA DE LUJO S16<\/h3>\n<p>Fruto de una intensa campa\u00f1a de muestreo de 3 meses, el desarrollo de nuestra cera de soja S16 Deluxe ha contado con la ayuda de fabricantes de velas reales y cotidianos junto con un laboratorio homologado por el gobierno australiano con sede en Melbourne.<br \/>\nNuestra cera de soja S16 Deluxe, fabricada con productos naturales 100%, es similar en su formulaci\u00f3n a otra cera popular, pero recientemente descatalogada.<br \/>\nEl acabado cremoso de la soja que se obtiene con la S16 es extraordinario. Las velas producidas con soja S16 Deluxe est\u00e1n listas para colocarse en cualquier estante de boutique de alta gama. La soja S16 Deluxe tiene una combusti\u00f3n uniforme y calmante, una fant\u00e1stica adherencia al recipiente y un gran rendimiento general en lo que respecta a la difusi\u00f3n del aroma.<\/p>\n<p>Esta variedad, tal como se anuncia, es una cera completamente vegetal y natural.<br \/>\nContiene aceite de soja hidratado y un aditivo exclusivo de origen vegetal.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>S16 Deluxe Soy se ha creado mediante la intersecci\u00f3n de la naturaleza y la ciencia.<\/strong><\/p>\n<p>Mediante la hidrogenaci\u00f3n de un subproducto del proceso de recolecci\u00f3n de la soja, podemos utilizar este compuesto m\u00e1s grueso y resistente para endurecer y estabilizar la cera de soja natural, lo que da como resultado un producto natural 100% que funciona de forma constante como deber\u00eda hacerlo cualquier cera de calidad.<\/p>\n<p>Este proceso muy cient\u00edfico y cuidadosamente medido nos deja una cera \u00fanica cuyas caracter\u00edsticas incluyen:<\/p>\n<ul>\n<li>Fabricado \u00edntegramente con productos naturales<\/li>\n<li>Precioso acabado cremoso de soja<\/li>\n<li>Fraguado suave tras la combusti\u00f3n<\/li>\n<li>Alta tolerancia a las fragancias para una cera de soja (6-8%)<\/li>\n<li>Gran adherencia del envase<\/li>\n<li>Propiedades antiencogimiento y antihielo<\/li>\n<li>Fant\u00e1stica absorci\u00f3n del aceite que da como resultado un incre\u00edble lanzamiento de olor en fr\u00edo y en caliente<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>PRUEBAS<\/h3>\n<hr \/>\n<div><\/div>\n<p>La magia de hacer velas est\u00e1 en tus propias pruebas.<br \/>\nPara encontrar las mezclas, las mechas, los tarros, las temperaturas, los porcentajes y las fragancias que le den los mejores resultados, le animamos a que realice muchas pruebas y ensayos diferentes para conseguir su vela perfecta lista para usar.<\/p>\n<p><a href=\"https:\/\/luxurycandlesupplies.eu\/es\/candle-testing-sheet\/\" target=\"_blank\" rel=\"noopener\">Haga clic para descargar gratuitamente la hoja de trabajo de prueba de velas de All Seasons Wax Company<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>INFORMACI\u00d3N T\u00c9CNICA<\/h3>\n<hr \/>\n<div><\/div>\n<p><strong>Punto de fusi\u00f3n<\/strong>: Temperatura m\u00e1xima de fusi\u00f3n 50,06\u00b0C<br \/>\n<strong>Punto de congelaci\u00f3n<\/strong>: Temperatura de congelaci\u00f3n 36,3\u00b0C<br \/>\n<strong>Rango de calentamiento sugerido<\/strong>: Rango de calentamiento 62\u00b0C - 72\u00b0C<br \/>\n<strong>Rango de vertido sugerido<\/strong>: 45\u00b0C - 55\u00b0C<br \/>\n<strong>Carga de fragancia m\u00e1xima sugerida<\/strong>6-8% - depende de la potencia de la fragancia, por lo que es necesario realizar pruebas.<br \/>\n<strong>Contenido<\/strong>: 100% Aceite de soja hidrogenado mezclado con la adici\u00f3n de un aditivo vegetal \u00fanico.<\/p>\n<p>**Calentar a m\u00e1s de 85\u00b0C durante demasiado tiempo puede provocar la decoloraci\u00f3n de la cera.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/luxurycandlesupplies.com.au\/wp-content\/uploads\/2021\/01\/Safety-Data-Sheet-S16.pdf\" target=\"_blank\" rel=\"noopener\">Descargar la ficha de datos de seguridad (FDS)<\/a><br \/>\n<a id=\"yui_3_17_2_1_1744291874848_317\" href=\"https:\/\/luxurycandlesupplies.com.au\/wp-content\/uploads\/2021\/01\/COA_ASWC_A05-S16-S100-A27_v2.pdf\" target=\"_blank\" rel=\"noopener\">Descargar el Certificado de An\u00e1lisis (COA)<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3>NUESTRA RECOMENDACI\u00d3N<\/h3>\n<hr \/>\n<div><\/div>\n<p>S16 Deluxe Soya es una cera duradera y resistente con un fant\u00e1stico aspecto tras el vertido.<br \/>\nLe sugerimos que tenga cuidado al preparar las condiciones de vertido de sus velas y que realice siempre una prueba en esas condiciones antes de producir en serie cualquiera de sus gamas de velas.<br \/>\nNuestras pruebas han indicado que 22\u00b0C es la temperatura ambiente ideal para fabricar velas de soja.<\/p>\n<p>Recomendamos la cera de soja S16 Deluxe a todos los fabricantes de velas, ya que se trata de una cera con un equilibrio \u00fanico y un rendimiento excelente en todos los aspectos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>Esta cera es vegana, no contiene ning\u00fan producto de origen animal, es de origen sostenible y est\u00e1 libre de crueldad.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-71\" src=\"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2021\/06\/Knipsel.jpg\" alt=\"\" width=\"80\" height=\"44\" \/><\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Fruto de una intensa campa\u00f1a de muestreo de 3 meses, el desarrollo de nuestra cera de soja S16 Deluxe ha contado con la ayuda de fabricantes de velas reales y cotidianos junto con un laboratorio homologado por el gobierno australiano con sede en Melbourne.<br \/>\nNuestra cera de soja S16 Deluxe, fabricada con productos naturales 100%, es similar en su formulaci\u00f3n a otra cera popular, pero recientemente descatalogada.<br \/>\nEl acabado cremoso de la soja que se obtiene con la S16 es extraordinario. Las velas producidas con soja S16 Deluxe est\u00e1n listas para colocarse en cualquier estante de boutique de alta gama. La soja S16 Deluxe tiene una combusti\u00f3n uniforme y calmante, una fant\u00e1stica adherencia al recipiente y un gran rendimiento general en lo que respecta a la difusi\u00f3n del aroma.<\/p>\n<p>Esta variedad, tal como se anuncia, es una cera completamente vegetal y natural.<br \/>\nContiene aceite de soja hidratado y un aditivo exclusivo de origen vegetal.<\/p>\n<p><strong>S16 Deluxe Soy se ha creado mediante la intersecci\u00f3n de la naturaleza y la ciencia.<\/strong><\/p>\n<p>Mediante la hidrogenaci\u00f3n de un subproducto del proceso de recolecci\u00f3n de la soja, podemos utilizar este compuesto m\u00e1s grueso y resistente para endurecer y estabilizar la cera de soja natural, lo que da como resultado un producto natural 100% que funciona de forma constante como deber\u00eda hacerlo cualquier cera de calidad.<\/p>\n<blockquote><p>Esta cera es vegana, no contiene ning\u00fan producto de origen animal, es de origen sostenible y est\u00e1 libre de crueldad.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-71\" src=\"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2021\/06\/Knipsel.jpg\" alt=\"\" width=\"80\" height=\"44\" \/><\/p><\/blockquote>","protected":false},"featured_media":140,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[17,45],"product_tag":[19,30,20,27,22],"class_list":["post-83","product","type-product","status-publish","has-post-thumbnail","product_cat-wax","product_cat-s16-deluxe-soy","product_tag-all-seasons-wax","product_tag-s16-wax","product_tag-soy-wax","product_tag-vegan-wax","product_tag-wax","product_shipping_class-pallet-if-24plus","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<title>S16 Deluxe Soy - 15kg - Antwerp Luxury Candle Supplies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxurycandlesupplies.eu\/es\/producto\/s16-soja-de-lujo-15kg\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S16 Deluxe Soy - 15kg - Antwerp Luxury Candle Supplies\" \/>\n<meta property=\"og:description\" content=\"The result of an intense 3-month sampling campaign, our S16 Deluxe Soy wax\u2019s development has been assisted by real, everyday candle makers alongside an Australian government approved lab based in Melbourne. Made from 100% natural, plant based products our S16 Deluxe Soy wax is similar in it\u2019s formulation to another popular, yet recently discontinued wax. The creamy soy finish you will see when using S16 is nothing short of remarkable! Candles produced with S16 Deluxe Soy are ready to be placed on any high-end boutique shelf. S16 Deluxe Soy has an even and calming burn, fantastic container adhesion and great overall performance in regards to scent throw.  This variety, as advertised \u2013 is a completely plant based, natural wax. Containing hydrated soya oil and unique vegetable sourced additive.  S16 Deluxe Soy has been created through the intersection of nature and science.  By hydrogenating a by-product of the soy harvesting process, we\u2019re able to use this thicker and tougher compound to harden and stabilise the natural soy wax resulting in a 100% natural product that performs consistently like any great wax should. This wax is vegan, does not contain any animal bi-products, is sustainbly sourced and cruelty free.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxurycandlesupplies.eu\/es\/producto\/s16-soja-de-lujo-15kg\/\" \/>\n<meta property=\"og:site_name\" content=\"Antwerp Luxury Candle Supplies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Antwerpluxurycandlesupplies\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T08:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2021\/07\/s16BOX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/\",\"name\":\"S16 Deluxe Soy - 15kg - Antwerp Luxury Candle Supplies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/app\\\/uploads\\\/2021\\\/07\\\/s16BOX.jpg\",\"datePublished\":\"2021-07-01T09:16:40+00:00\",\"dateModified\":\"2026-07-15T08:15:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/app\\\/uploads\\\/2021\\\/07\\\/s16BOX.jpg\",\"contentUrl\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/app\\\/uploads\\\/2021\\\/07\\\/s16BOX.jpg\",\"width\":300,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product\\\/s16-deluxe-soy-15kg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S16 Deluxe Soy &#8211; 15kg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#website\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/\",\"name\":\"Antwerp Luxury Candle Supplies\",\"description\":\"Distributor of all seasons soy wax\",\"publisher\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#organization\",\"name\":\"Antwerp Luxury Candle Supplies\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/app\\\/uploads\\\/2022\\\/03\\\/antwerp-luxury-candle-supplies-1x.png\",\"contentUrl\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/app\\\/uploads\\\/2022\\\/03\\\/antwerp-luxury-candle-supplies-1x.png\",\"width\":330,\"height\":60,\"caption\":\"Antwerp Luxury Candle Supplies\"},\"image\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Antwerpluxurycandlesupplies\\\/\",\"https:\\\/\\\/www.instagram.com\\\/antwerp_luxury_candle_supplies\\\/\",\"https:\\\/\\\/pin.it\\\/7joOXRW\"]}]}<\/script>","yoast_head_json":{"title":"S16 Soja de Lujo - 15kg - Antwerp Luxury Candle Supplies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxurycandlesupplies.eu\/es\/producto\/s16-soja-de-lujo-15kg\/","og_locale":"es_ES","og_type":"article","og_title":"S16 Deluxe Soy - 15kg - Antwerp Luxury Candle Supplies","og_description":"The result of an intense 3-month sampling campaign, our S16 Deluxe Soy wax\u2019s development has been assisted by real, everyday candle makers alongside an Australian government approved lab based in Melbourne. Made from 100% natural, plant based products our S16 Deluxe Soy wax is similar in it\u2019s formulation to another popular, yet recently discontinued wax. The creamy soy finish you will see when using S16 is nothing short of remarkable! Candles produced with S16 Deluxe Soy are ready to be placed on any high-end boutique shelf. S16 Deluxe Soy has an even and calming burn, fantastic container adhesion and great overall performance in regards to scent throw.  This variety, as advertised \u2013 is a completely plant based, natural wax. Containing hydrated soya oil and unique vegetable sourced additive.  S16 Deluxe Soy has been created through the intersection of nature and science.  By hydrogenating a by-product of the soy harvesting process, we\u2019re able to use this thicker and tougher compound to harden and stabilise the natural soy wax resulting in a 100% natural product that performs consistently like any great wax should. This wax is vegan, does not contain any animal bi-products, is sustainbly sourced and cruelty free.","og_url":"https:\/\/luxurycandlesupplies.eu\/es\/producto\/s16-soja-de-lujo-15kg\/","og_site_name":"Antwerp Luxury Candle Supplies","article_publisher":"https:\/\/www.facebook.com\/Antwerpluxurycandlesupplies\/","article_modified_time":"2026-07-15T08:15:28+00:00","og_image":[{"width":300,"height":225,"url":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2021\/07\/s16BOX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/","url":"https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/","name":"S16 Soja de Lujo - 15kg - Antwerp Luxury Candle Supplies","isPartOf":{"@id":"https:\/\/luxurycandlesupplies.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/#primaryimage"},"image":{"@id":"https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/#primaryimage"},"thumbnailUrl":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2021\/07\/s16BOX.jpg","datePublished":"2021-07-01T09:16:40+00:00","dateModified":"2026-07-15T08:15:28+00:00","breadcrumb":{"@id":"https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/#primaryimage","url":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2021\/07\/s16BOX.jpg","contentUrl":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2021\/07\/s16BOX.jpg","width":300,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/luxurycandlesupplies.eu\/product\/s16-deluxe-soy-15kg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/luxurycandlesupplies.eu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/luxurycandlesupplies.eu\/shop\/"},{"@type":"ListItem","position":3,"name":"S16 Deluxe Soy &#8211; 15kg"}]},{"@type":"WebSite","@id":"https:\/\/luxurycandlesupplies.eu\/#website","url":"https:\/\/luxurycandlesupplies.eu\/","name":"Suministros para velas de lujo de Amberes","description":"Distribuidor de cera de soja para todas las estaciones","publisher":{"@id":"https:\/\/luxurycandlesupplies.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxurycandlesupplies.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/luxurycandlesupplies.eu\/#organization","name":"Suministros para velas de lujo de Amberes","url":"https:\/\/luxurycandlesupplies.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxurycandlesupplies.eu\/#\/schema\/logo\/image\/","url":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2022\/03\/antwerp-luxury-candle-supplies-1x.png","contentUrl":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2022\/03\/antwerp-luxury-candle-supplies-1x.png","width":330,"height":60,"caption":"Antwerp Luxury Candle Supplies"},"image":{"@id":"https:\/\/luxurycandlesupplies.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Antwerpluxurycandlesupplies\/","https:\/\/www.instagram.com\/antwerp_luxury_candle_supplies\/","https:\/\/pin.it\/7joOXRW"]}]}},"_links":{"self":[{"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/product\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/media\/140"}],"wp:attachment":[{"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/product_brand?post=83"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/product_cat?post=83"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/luxurycandlesupplies.eu\/es\/wp-json\/wp\/v2\/product_tag?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}