{"id":1644,"count":6,"description":"","link":"https:\/\/luxurycandlesupplies.eu\/fr\/product-category\/fragrance-bases\/","name":"Bases de parfum","slug":"bases-parfumees","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":5,"acf":[],"yoast_head":"<title>Fragrance Bases Archives - Antwerp Luxury Candle Supplies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxurycandlesupplies.eu\/fr\/categorie-de-produits\/bases-parfumees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fragrance Bases Archives - Antwerp Luxury Candle Supplies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxurycandlesupplies.eu\/fr\/categorie-de-produits\/bases-parfumees\/\" \/>\n<meta property=\"og:site_name\" content=\"Antwerp Luxury Candle Supplies\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product-category\\\/fragrance-bases\\\/\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product-category\\\/fragrance-bases\\\/\",\"name\":\"Fragrance Bases Archives - Antwerp Luxury Candle Supplies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product-category\\\/fragrance-bases\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/product-category\\\/fragrance-bases\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fragrance Bases\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#website\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/\",\"name\":\"Antwerp Luxury Candle Supplies\",\"description\":\"Distributor of all seasons soy wax\",\"publisher\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#organization\",\"name\":\"Antwerp Luxury Candle Supplies\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/app\\\/uploads\\\/2022\\\/03\\\/antwerp-luxury-candle-supplies-1x.png\",\"contentUrl\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/app\\\/uploads\\\/2022\\\/03\\\/antwerp-luxury-candle-supplies-1x.png\",\"width\":330,\"height\":60,\"caption\":\"Antwerp Luxury Candle Supplies\"},\"image\":{\"@id\":\"https:\\\/\\\/luxurycandlesupplies.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Antwerpluxurycandlesupplies\\\/\",\"https:\\\/\\\/www.instagram.com\\\/antwerp_luxury_candle_supplies\\\/\",\"https:\\\/\\\/pin.it\\\/7joOXRW\"]}]}<\/script>","yoast_head_json":{"title":"Archives des bases de parfum - Antwerp Luxury Candle Supplies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxurycandlesupplies.eu\/fr\/categorie-de-produits\/bases-parfumees\/","og_locale":"fr_FR","og_type":"article","og_title":"Fragrance Bases Archives - Antwerp Luxury Candle Supplies","og_url":"https:\/\/luxurycandlesupplies.eu\/fr\/categorie-de-produits\/bases-parfumees\/","og_site_name":"Antwerp Luxury Candle Supplies","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/luxurycandlesupplies.eu\/product-category\/fragrance-bases\/","url":"https:\/\/luxurycandlesupplies.eu\/product-category\/fragrance-bases\/","name":"Archives des bases de parfum - Antwerp Luxury Candle Supplies","isPartOf":{"@id":"https:\/\/luxurycandlesupplies.eu\/#website"},"breadcrumb":{"@id":"https:\/\/luxurycandlesupplies.eu\/product-category\/fragrance-bases\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/luxurycandlesupplies.eu\/product-category\/fragrance-bases\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/luxurycandlesupplies.eu\/"},{"@type":"ListItem","position":2,"name":"Fragrance Bases"}]},{"@type":"WebSite","@id":"https:\/\/luxurycandlesupplies.eu\/#website","url":"https:\/\/luxurycandlesupplies.eu\/","name":"Anvers Fournitures de bougies de luxe","description":"Distributeur de cire de soja toutes saisons","publisher":{"@id":"https:\/\/luxurycandlesupplies.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxurycandlesupplies.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/luxurycandlesupplies.eu\/#organization","name":"Anvers Fournitures de bougies de luxe","url":"https:\/\/luxurycandlesupplies.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/luxurycandlesupplies.eu\/#\/schema\/logo\/image\/","url":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2022\/03\/antwerp-luxury-candle-supplies-1x.png","contentUrl":"https:\/\/luxurycandlesupplies.eu\/app\/uploads\/2022\/03\/antwerp-luxury-candle-supplies-1x.png","width":330,"height":60,"caption":"Antwerp Luxury Candle Supplies"},"image":{"@id":"https:\/\/luxurycandlesupplies.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Antwerpluxurycandlesupplies\/","https:\/\/www.instagram.com\/antwerp_luxury_candle_supplies\/","https:\/\/pin.it\/7joOXRW"]}]}},"_links":{"self":[{"href":"https:\/\/luxurycandlesupplies.eu\/fr\/wp-json\/wp\/v2\/product_cat\/1644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxurycandlesupplies.eu\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/luxurycandlesupplies.eu\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/luxurycandlesupplies.eu\/fr\/wp-json\/wp\/v2\/product?product_cat=1644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}